{"id":130,"date":"2022-10-22T22:23:46","date_gmt":"2022-10-22T22:23:46","guid":{"rendered":"https:\/\/help.cleanster.com\/?post_type=help&#038;p=130"},"modified":"2022-11-25T17:07:26","modified_gmt":"2022-11-25T17:07:26","slug":"cookies-policy","status":"publish","type":"help","link":"https:\/\/help.cleanster.com\/es\/cookies-policy\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><br>Pol\u00edtica de cookies<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los sitios web mantenidos por Cleanster.com (colectivamente, el &quot;Sitio&quot;) utilizan varias cookies diferentes. Esta Pol\u00edtica de Cookies explica lo siguiente:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>&nbsp; &nbsp; &nbsp;&nbsp;&nbsp;\u00bfQu\u00e9 son las cookies?<\/li>\n\n\n\n<li>&nbsp; &nbsp; &nbsp; &nbsp;Cookies que usamos y por qu\u00e9 las usamos<\/li>\n\n\n\n<li>&nbsp; &nbsp; &nbsp; &nbsp;Derecho de los usuarios de la UE a rechazar las cookies<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQU\u00c9 SON LAS COOKIES?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies son peque\u00f1os archivos que se descargan en su dispositivo cuando visita un sitio web. Luego, la cookie env\u00eda informaci\u00f3n al sitio web de origen en cada visita posterior, o a otro sitio web que reconozca esa cookie. Las cookies son \u00fatiles porque permiten que un sitio web reconozca el dispositivo de un usuario. Puede encontrar m\u00e1s informaci\u00f3n sobre las cookies en:<a href=\"http:\/\/www.allaboutcookies.org\/\">www.allaboutcookies.org<\/a>&nbsp;y&nbsp;<a href=\"http:\/\/www.youronlinechoices.eu\/\">www.youronlinechoices.eu<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies realizan muchas funciones diferentes, como permitirle navegar entre p\u00e1ginas de manera eficiente, recordar sus preferencias y, en general, mejorar la experiencia del usuario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>COOKIES Y POR QU\u00c9 LAS UTILIZAMOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies se pueden categorizar seg\u00fan qui\u00e9n coloca la cookie en la computadora del usuario (u otro dispositivo que el usuario usa para navegar por el sitio web).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cookies de origen<\/strong>&nbsp;son cookies colocadas por la parte que opera el sitio web. Por ejemplo, cualquier cookie que nosotros (Cleanster.com) coloquemos en su computadora desde nuestro Sitio son cookies propias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cookies de terceros<\/strong>&nbsp;son cookies colocadas desde un sitio web por una parte que no posee ni opera ese sitio web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Usamos solo cookies propias en nuestro Sitio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies tambi\u00e9n se clasifican a menudo por funci\u00f3n. Utilizamos cuatro tipos de cookies por funci\u00f3n en nuestro Sitio:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Cookies esenciales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son cookies estrictamente necesarias para el funcionamiento del sitio web o para la prestaci\u00f3n de servicios solicitados por un usuario individual. Por ejemplo, utilizamos una cookie que recuerda que ha iniciado sesi\u00f3n en el Sitio hasta que cierra la sesi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si se suscribe a nuestro programa de mensajes de texto, se pueden usar cookies para personalizar su experiencia (p. ej., enviarle mensajes de texto personalizados)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Cookies Anal\u00edticas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas cookies recopilan informaci\u00f3n sobre c\u00f3mo los visitantes usan un sitio web, por ejemplo, qu\u00e9 p\u00e1ginas visitan los visitantes con m\u00e1s frecuencia y si los visitantes reciben mensajes de error de las p\u00e1ginas web. Las cookies anal\u00edticas no recopilan informaci\u00f3n que identifique a un visitante. Toda la informaci\u00f3n que recogen las cookies anal\u00edticas es agregada y, por tanto, an\u00f3nima. Estas cookies se utilizan \u00fanicamente para mejorar el funcionamiento de un sitio web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Usamos cookies proporcionadas por proveedores de servicios externos, incluidos Google Analytics, Optimizely y New Relic, para ayudarnos a analizar c\u00f3mo los usuarios usan el Sitio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies de Google Analytics recopilan datos vinculados a la direcci\u00f3n IP de un usuario, como el tiempo que un usuario pasa en una p\u00e1gina, las p\u00e1ginas que visita y los sitios web que visita antes y despu\u00e9s de visitar el Sitio. Puede oponerse a la recopilaci\u00f3n de su informaci\u00f3n por parte de Google Analytics haciendo clic en&nbsp;<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=en\">aqu\u00ed<\/a>. Colocamos cookies proporcionadas por Optimizely para probar si los cambios que hemos realizado en el Sitio funcionan correctamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que las cookies proporcionadas por Google Analytics y Optimizely, las cookies proporcionadas por New Relic recopilan informaci\u00f3n sobre su visita al Sitio, como los retrasos que puede experimentar al usar las funciones del Sitio. Las cookies de New Relic asignan un n\u00famero de identificaci\u00f3n, llamado &quot;ID de sesi\u00f3n&quot;, a su visita a nuestro Sitio. La informaci\u00f3n recopilada sobre su visita se env\u00eda a New Relic y se vincula a la identificaci\u00f3n de la sesi\u00f3n. Cada visita genera una nueva ID de sesi\u00f3n, y las ID de sesi\u00f3n entre diferentes visitas no est\u00e1n vinculadas a su identificaci\u00f3n. New Relic elimina la ID de sesi\u00f3n al final de su visita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies proporcionadas por cada proveedor de servicios de terceros env\u00edan la informaci\u00f3n que recopilan a ese proveedor de servicios de terceros. Por ejemplo, las cookies proporcionadas por Google Analytics env\u00edan informaci\u00f3n sobre las interacciones de su sitio a Google Analytics. Luego, cada proveedor de servicios externo recopila datos agregados utilizando la informaci\u00f3n recibida y nos env\u00eda informes sobre los datos agregados. Estos informes no se comparten con otras partes. Usamos los informes para ofrecer mejores experiencias y herramientas en el Sitio en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque estas cookies proporcionan informaci\u00f3n a proveedores de servicios de terceros, son cookies propias porque las colocamos nosotros mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Cookies funcionales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas cookies permiten que el sitio web recuerde las elecciones que hacen los usuarios y brinde funciones mejoradas y personalizadas. Por ejemplo, utilizamos cookies proporcionadas por Olark.com que le permiten continuar chateando con atenci\u00f3n al cliente cuando navega entre p\u00e1ginas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. Cookies de orientaci\u00f3n\/publicidad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies de segmentaci\u00f3n\/publicidad son cookies que se utilizan para ofrecer anuncios relevantes para el usuario. Recuerdan que un usuario visit\u00f3 un sitio web y comparti\u00f3 esta informaci\u00f3n con otras organizaciones, como proveedores de publicidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies de esta categor\u00eda pueden incluir cookies de remarketing. Estas son cookies que recuerdan que visit\u00f3 nuestro Sitio despu\u00e9s de que se fue. A veces recopilan informaci\u00f3n sobre las p\u00e1ginas de nuestro Sitio que visit\u00f3. Luego comparten esta informaci\u00f3n con nuestros proveedores externos, como AppNexus, Google, Nanigans, Facebook y Twitter. Con base en esta informaci\u00f3n, los proveedores externos le muestran anuncios en sitios web de terceros para productos de Cleanster.com que creemos que pueden interesarle seg\u00fan lo que vio en nuestro Sitio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puede rechazar el uso de cookies de Google visitando\u00a0<a href=\"http:\/\/www.google.com\/settings\/ads?hl=en&amp;sig=ACi0TCj3tYSWx1J-_py5kWT1_-bwSVlQ6_ctD3te7yK2M1nOjE8qqSPAFgD0ilTnZH6iRKipNQr3oHKqwYqeB9AJ6VnmkUfSZskoxWxZeLpChNWyCneYQQMHG2rpHJrxi_jE-Bv8LL8S0uqPcmcBA2zkPYibn6b5OwjEfvqbZTq7a_Muo-nZ-9GaW8xM7xt7asNUmDcB41Lg\">Configuraci\u00f3n de anuncios de Google<\/a>\u00a0aqu\u00ed. Tambi\u00e9n puede excluirse del uso por parte de otros anunciantes y proveedores de servicios externos, como AppNexus, de la informaci\u00f3n de las cookies colocadas por el Sitio visitando la p\u00e1gina de exclusi\u00f3n de Network Advertising Initiative (&quot;NAI&quot;). Sin embargo, no todos nuestros proveedores externos participan en el\u00a0<a href=\"http:\/\/www.networkadvertising.org\/choices\/\">P\u00e1gina de exclusi\u00f3n voluntaria de la iniciativa de publicidad en la red<\/a>. Algunos de estos anunciantes y\/o proveedores de servicios tambi\u00e9n pueden participar en el Programa de Autorregulaci\u00f3n para la Publicidad Comportamental en L\u00ednea de Digital Advertising Alliance (&quot;DAA&quot;). Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo puede ejercer ciertas opciones con respecto a la publicidad basada en intereses, incluido el uso de datos de dispositivos cruzados para publicar anuncios, visite http:\/\/www.aboutads.info\/choices\/ y http:\/\/www.aboutads. info\/appchoices para obtener informaci\u00f3n sobre el programa de exclusi\u00f3n voluntaria de la DAA espec\u00edficamente para aplicaciones m\u00f3viles (incluido el uso de la ubicaci\u00f3n precisa para anuncios de terceros). Tenga en cuenta que, incluso si puede optar por no recibir ciertos tipos de publicidad basada en intereses, puede continuar recibiendo otros tipos de anuncios. La exclusi\u00f3n solo significa que esos miembros seleccionados ya no deber\u00edan enviarle cierta publicidad basada en intereses, pero no significa que ya no recibir\u00e1 ning\u00fan contenido y\/o anuncios espec\u00edficos (por ejemplo, de otras redes publicitarias). Adem\u00e1s, si sus navegadores est\u00e1n configurados para rechazar las cookies cuando visita estas p\u00e1ginas web de exclusi\u00f3n voluntaria, o si posteriormente borra sus cookies, utiliza un dispositivo o navegador web diferente o utiliza un m\u00e9todo de acceso no basado en navegador (por ejemplo, aplicaci\u00f3n m\u00f3vil) , su opci\u00f3n de exclusi\u00f3n basada en el navegador NAI \/ DAA puede no ser efectiva o puede que ya no sea efectiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies tambi\u00e9n se pueden clasificar seg\u00fan el tiempo que permanecen en su dispositivo. Hay dos grandes categor\u00edas de duraci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Cookies persistentes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies persistentes permanecen en su dispositivo hasta que se eliminan manual o autom\u00e1ticamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Cookies de sesi\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cookies de sesi\u00f3n permanecen en su dispositivo hasta que cierra su navegador cuando se eliminan autom\u00e1ticamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizamos cookies de sesi\u00f3n y persistentes en nuestro Sitio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lugar de procesamiento de la informaci\u00f3n:<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n que recopilan nuestras cookies se procesa en servidores ubicados en Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DERECHO DE LOS USUARIOS DE LA UE A RECHAZAR LAS COOKIES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los usuarios de la Uni\u00f3n Europea (UE) tienen derecho a negarse a permitir que se coloquen cookies en el dispositivo que utilizan para acceder al Sitio. Describimos a continuaci\u00f3n c\u00f3mo los usuarios de la UE pueden rechazar las cookies utilizadas por nuestro sitio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rechazo de cookies a trav\u00e9s de la configuraci\u00f3n del navegador:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El men\u00fa Ayuda en la barra de men\u00fa de la mayor\u00eda de los navegadores le dir\u00e1 c\u00f3mo evitar que su navegador acepte nuevas cookies, c\u00f3mo hacer que el navegador le notifique cuando recibe una nueva cookie y c\u00f3mo deshabilitar las cookies por completo. Para obtener m\u00e1s informaci\u00f3n sobre el uso de la configuraci\u00f3n del navegador para rechazar las cookies, visite&nbsp;<a href=\"http:\/\/www.allaboutcookies.org\/\">www.allaboutcookies.org<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debe tener en cuenta que rechazar las cookies en la configuraci\u00f3n de su navegador puede significar que se perder\u00e1n las preferencias que estableci\u00f3 en este Sitio y que el Sitio podr\u00eda no funcionar tan bien. Adem\u00e1s, el uso de la configuraci\u00f3n del navegador para rechazar las cookies tambi\u00e9n puede hacer que su navegador rechace las cookies de todos los sitios web, no solo de este Sitio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfTIENE PREGUNTAS?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tiene alguna pregunta sobre nuestra Pol\u00edtica de cookies, haremos todo lo posible para responderla. Puede enviarnos un correo electr\u00f3nico a legal@cleanster.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ACTUALIZACIONES DE LA POL\u00cdTICA DE COOKIES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si cambiamos nuestra Pol\u00edtica de cookies, publicaremos esos cambios en esta p\u00e1gina y actualizaremos la fecha de modificaci\u00f3n de la Pol\u00edtica de cookies anterior. Si cambiamos materialmente esta Pol\u00edtica de cookies de una manera que afecte la forma en que usamos o divulgamos su informaci\u00f3n personal, se lo notificaremos publicando un aviso destacado de dichos cambios antes de realizarlos y indicando la fecha de vigencia de los cambios.<\/p>","protected":false},"featured_media":0,"template":"","categories":[19,17],"class_list":["post-130","help","type-help","status-publish","hentry","category-privacy","category-legal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cookies Policy - Cleanster.com Support | How can we help?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.cleanster.com\/es\/cookies-policy\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookies Policy\" \/>\n<meta property=\"og:description\" content=\"Cookies Policy Websites maintained by Cleanster.com (collectively the &#8220;Site&#8221;) use a number of different cookies. This Cookies Policy explains the following: WHAT ARE COOKIES? Cookies are small files that are downloaded to your device when you visit a website. The cookie then sends information back to the originating website on each subsequent visit, or to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.cleanster.com\/es\/cookies-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Cleanster.com Support | How can we help?\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-25T17:07:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/cookies-policy\\\/\",\"url\":\"https:\\\/\\\/help.cleanster.com\\\/cookies-policy\\\/\",\"name\":\"Cookies Policy - Cleanster.com Support | How can we help?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/#website\"},\"datePublished\":\"2022-10-22T22:23:46+00:00\",\"dateModified\":\"2022-11-25T17:07:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/cookies-policy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.cleanster.com\\\/cookies-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/cookies-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/help.cleanster.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookies Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/#website\",\"url\":\"https:\\\/\\\/help.cleanster.com\\\/\",\"name\":\"Cleanster.com Support | How can we help?\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.cleanster.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/#organization\",\"name\":\"Cleanster.com Support | How can we help?\",\"url\":\"https:\\\/\\\/help.cleanster.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/help.cleanster.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/cleanster.com_.svg\",\"contentUrl\":\"https:\\\/\\\/help.cleanster.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/cleanster.com_.svg\",\"caption\":\"Cleanster.com Support | How can we help?\"},\"image\":{\"@id\":\"https:\\\/\\\/help.cleanster.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de cookies - Soporte de Cleanster.com | \u00bfEn qu\u00e9 podemos ayudarle?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.cleanster.com\/es\/cookies-policy\/","og_locale":"es_MX","og_type":"article","og_title":"Cookies Policy","og_description":"Cookies Policy Websites maintained by Cleanster.com (collectively the &#8220;Site&#8221;) use a number of different cookies. This Cookies Policy explains the following: WHAT ARE COOKIES? Cookies are small files that are downloaded to your device when you visit a website. The cookie then sends information back to the originating website on each subsequent visit, or to [&hellip;]","og_url":"https:\/\/help.cleanster.com\/es\/cookies-policy\/","og_site_name":"Cleanster.com Support | How can we help?","article_modified_time":"2022-11-25T17:07:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/help.cleanster.com\/cookies-policy\/","url":"https:\/\/help.cleanster.com\/cookies-policy\/","name":"Pol\u00edtica de cookies - Soporte de Cleanster.com | \u00bfEn qu\u00e9 podemos ayudarle?","isPartOf":{"@id":"https:\/\/help.cleanster.com\/#website"},"datePublished":"2022-10-22T22:23:46+00:00","dateModified":"2022-11-25T17:07:26+00:00","breadcrumb":{"@id":"https:\/\/help.cleanster.com\/cookies-policy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.cleanster.com\/cookies-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/help.cleanster.com\/cookies-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/help.cleanster.com\/"},{"@type":"ListItem","position":2,"name":"Cookies Policy"}]},{"@type":"WebSite","@id":"https:\/\/help.cleanster.com\/#website","url":"https:\/\/help.cleanster.com\/","name":"Cleanster.com Soporte | \u00bfC\u00f3mo podemos ayudar?","description":"","publisher":{"@id":"https:\/\/help.cleanster.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.cleanster.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/help.cleanster.com\/#organization","name":"Cleanster.com Soporte | \u00bfC\u00f3mo podemos ayudar?","url":"https:\/\/help.cleanster.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/help.cleanster.com\/#\/schema\/logo\/image\/","url":"https:\/\/help.cleanster.com\/wp-content\/uploads\/2022\/11\/cleanster.com_.svg","contentUrl":"https:\/\/help.cleanster.com\/wp-content\/uploads\/2022\/11\/cleanster.com_.svg","caption":"Cleanster.com Support | How can we help?"},"image":{"@id":"https:\/\/help.cleanster.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/help.cleanster.com\/es\/wp-json\/wp\/v2\/help\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.cleanster.com\/es\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/help.cleanster.com\/es\/wp-json\/wp\/v2\/types\/help"}],"wp:attachment":[{"href":"https:\/\/help.cleanster.com\/es\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.cleanster.com\/es\/wp-json\/wp\/v2\/categories?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}